{"id":73,"date":"2025-11-13T07:00:20","date_gmt":"2025-11-13T07:00:20","guid":{"rendered":"https:\/\/soil-stabilisor.com\/?page_id=73"},"modified":"2026-08-03T06:28:47","modified_gmt":"2026-08-03T06:28:47","slug":"home","status":"publish","type":"page","link":"https:\/\/soil-stabilisor.com\/it\/","title":{"rendered":"Casa"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Header Section&#8221; _builder_version=&#8221;4.8.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(20,61,88,0.65)&#8221; background_color_gradient_end=&#8221;#143d58&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/rock-rake.webp&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;16vw|0px|16vw|0px&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;rgba(5,41,66,0.3)&#8221; bottom_divider_height=&#8221;50%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;4%&#8221; animation_starting_opacity=&#8221;100%&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Header Row&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|||&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;8%&#8221; make_fullwidth=&#8221;on&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Page Heading &#038; Subhead&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Montserrat|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;8vw&#8221; header_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;|||&#8221; header_font_size_tablet=&#8221;50px&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_line_height_tablet=&#8221;1.1em&#8221; header_line_height_phone=&#8221;1.2em&#8221; header_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h1>Stabilizzatore del terreno<\/h1>\n<p>India Watanabe Soil Stabilizer Co.,Ltd<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;book an appointment&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;CTA Button&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;30px|||&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; use_custom_gutter=&#8221;on&#8221; specialty=&#8221;on&#8221; padding_top_1=&#8221;0px&#8221; padding_top_2=&#8221;80px&#8221; padding_right_2=&#8221;10%&#8221; padding_bottom_2=&#8221;0px&#8221; padding_2_tablet=&#8221;0px|||10%&#8221; padding_2_phone=&#8221;|||&#8221; padding_2_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#f2f6f9&#8243; background_color_gradient_end=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;25%&#8221; background_color_gradient_end_position=&#8221;25%&#8221; inner_width=&#8221;100%&#8221; inner_max_width=&#8221;100%&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;80px|80px|80px|80px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;120px|0px|120px|0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;1%&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/rock-pickers.webp&#8221; title_text=&#8221;rock pickers&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;60px|||||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;3.25&#8243; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_phone=&#8221;|||&#8221; locked=&#8221;off&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>Pro Tractor Rock Crusher e stabilizzatore del terreno \u2013 Produttore indiano<\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraph&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;||0px|||&#8221;]Welcome to the leading Indian hub for heavy-duty soil stabilization equipment and rock crushing machinery. As the dedicated subsidiary of the global mechanical powerhouse, Watanabe, India Watanabe Soil Stabilizer Co., Ltd. is your trusted India Manufacturer and supplier for engineering-grade solutions that transform challenging terrains into stable, arable, and construction-ready land. Our machinery is rigorously engineered to meet the demanding requirements of the Indian civil infrastructure and agricultural sectors, designed to effortlessly handle the diverse, challenging soil and rock conditions across the subcontinent, from the basalt terrain of Maharashtra to the rocky landscapes of Karnataka.[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner make_equal=&#8221;on&#8221; _builder_version=&#8221;3.25&#8243; max_width=&#8221;800px&#8221; custom_padding=&#8221;|||&#8221; locked=&#8221;off&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Why Choose India Watanabe: Precision, Power, and Local Expertise&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%173%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]We combine advanced Brazilian engineering with deep local application knowledge to deliver exceptional value. Below are the core technical specifications and product categories that position our machinery as the superior choice in the competitive Indian market.[\/et_pb_blurb][et_pb_button button_text=&#8221;Learn More&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#a5b9cc&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;|||46px&#8221; custom_margin_tablet=&#8221;||40px|&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; button_text_color_hover=&#8221;#e09900&#8243; button_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; locked=&#8221;off&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#e09900&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;CTA Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_end=&#8221;#f2f6f9&#8243; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;75%&#8221; background_color_gradient_end_position=&#8221;75%&#8221; custom_padding=&#8221;120px|0px|120px|0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;1%&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; admin_label=&#8221;CTA Row&#8221; _builder_version=&#8221;3.25&#8243; background_color_gradient_direction=&#8221;90deg&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;120px|||&#8221; custom_padding_phone=&#8221;120px|0px|0px|0px&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;80px|||12%&#8221; custom_padding_tablet=&#8221;|10%||10%&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;||20px|&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;0px|10%||70px&#8221; custom_padding_phone=&#8221;0px|10%||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>Comprendere le attrezzature per la stabilizzazione del terreno<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_color=&#8221;#21323d&#8221; header_2_font_size=&#8221;40px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|100px||70px&#8221; custom_padding_phone=&#8221;|||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p data-path-to-node=\"40\">Per ottenere una preparazione del terreno superiore, comprendere le sottili differenze e gli usi sovrapposti tra uno stabilizzatore del terreno dedicato e uno <b>macchina frantumatrice di rocce<\/b> \u00e8 vitale. <span class=\"citation-37 citation-end-37\">La nostra gamma comprende vari approcci meccanici per soddisfare esigenze di progetto specifiche<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"71\"><\/sup><\/source-footnote><\/span>.<sources-carousel-inline ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c832468483=\"\"><source-inline-chips _ngcontent-ng-c832468483=\"\" _nghost-ng-c2631690858=\"\" class=\"ng-star-inserted\"><source-inline-chip _ngcontent-ng-c2631690858=\"\" _nghost-ng-c661034879=\"\" class=\"ng-star-inserted\"><\/source-inline-chip><\/source-inline-chips><\/sources-carousel-inline><\/p>\n<p>&nbsp;<\/p>\n<p data-path-to-node=\"42\">\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;book an appointment&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;30px|||&#8221; custom_margin_tablet=&#8221;||120px|70px&#8221; custom_margin_phone=&#8221;||120px|50px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/potato-harvest-for-big-bags.webp&#8221; title_text=&#8221;potato harvest for big bag&#8217;s&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;CTA Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_end=&#8221;#f2f6f9&#8243; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;75%&#8221; background_color_gradient_end_position=&#8221;75%&#8221; custom_padding=&#8221;0px|0px|120px|0px||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;1%&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; admin_label=&#8221;CTA Row&#8221; _builder_version=&#8221;3.25&#8243; background_color_gradient_direction=&#8221;90deg&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;120px|||&#8221; custom_padding_phone=&#8221;120px|0px|0px|0px&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;80px|||12%&#8221; custom_padding_tablet=&#8221;|10%||10%&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;25px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;-78px||20px|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;0px|10%||70px&#8221; custom_padding_phone=&#8221;0px|10%||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h3><strong>Per principio di funzionamento: stabilizzatore vs. frantoio<\/strong><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_color=&#8221;#21323d&#8221; header_2_font_size=&#8221;40px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|100px||70px&#8221; custom_padding_phone=&#8221;|||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p data-path-to-node=\"43\"><span class=\"citation-35\">UN <\/span><b><span class=\"citation-35\">stabilizzatore del terreno<\/span><\/b><span class=\"citation-35 citation-end-35\"> si concentra sulla miscelazione di leganti (come la stabilizzazione del terreno con calce o la stabilizzazione del terreno con cemento)<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"73\"><\/sup><\/source-footnote><\/span><span class=\"citation-34 citation-end-34\">) nel materiale del terreno esistente per migliorarne la capacit\u00e0 portante e la resistenza all'umidit\u00e0<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"74\"><\/sup><\/source-footnote><\/span>L'obiettivo \u00e8 ottenere una matrice del suolo uniforme e chimicamente migliorata. <span class=\"citation-33 interactive-span-hovered\">Al contrario, un <\/span><b><span class=\"citation-33 interactive-span-hovered\">frantoio per rocce<\/span><\/b><span class=\"citation-33 interactive-span-hovered\"> (come il nostro <\/span><b><span class=\"citation-33 interactive-span-hovered\">THOR<\/span><\/b><span class=\"citation-33 citation-end-33 interactive-span-hovered\"> serie) \u00e8 progettato per ridurre meccanicamente grandi pietre e detriti in aggregati pi\u00f9 fini e utilizzabili, che a loro volta agiscono come una forma di stabilizzazione del suolo<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"75\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"75\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"75\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"75\"><\/sup><\/source-footnote><\/span>.<\/p>\n<p data-path-to-node=\"44\"><span class=\"citation-32 interactive-span-hovered\">Nostro <\/span><b><span class=\"citation-32 interactive-span-hovered\">frantoio portatile per rocce<\/span><\/b><span class=\"citation-32 interactive-span-hovered\"> I modelli offrono il meglio di entrambi i mondi, dotati di robusti rotori di frantumazione in grado di miscelare terreni profondi e polverizzare simultaneamente rocce e pietre, rendendoli un mezzo a duplice scopo <\/span><b><span class=\"citation-32 interactive-span-hovered\">stabilizzatore del terreno<\/span><\/b><span class=\"citation-32 citation-end-32 interactive-span-hovered\"> soluzione<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"76\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"76\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"76\"><\/sup><\/source-footnote><source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"76\"><\/sup><\/source-footnote><\/span>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/psw-3200-rotavator.webp&#8221; title_text=&#8221;psw-3200 rotavator&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; use_custom_gutter=&#8221;on&#8221; specialty=&#8221;on&#8221; padding_top_1=&#8221;0px&#8221; padding_top_2=&#8221;80px&#8221; padding_right_2=&#8221;10%&#8221; padding_bottom_2=&#8221;0px&#8221; padding_2_tablet=&#8221;0px|||10%&#8221; padding_2_phone=&#8221;|||&#8221; padding_2_last_edited=&#8221;on|tablet&#8221; admin_label=&#8221;About Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;#f2f6f9&#8243; background_color_gradient_end=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;25%&#8221; background_color_gradient_end_position=&#8221;25%&#8221; inner_width=&#8221;100%&#8221; inner_max_width=&#8221;100%&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;80px|80px|80px|80px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;0px|0px|120px|0px||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; animation_intensity_slide=&#8221;1%&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/destroyer-2.0-compost-barn.webp&#8221; alt=&#8221;destroyer 2.0 compost barn&#8221; title_text=&#8221;destroyer 2.0 compost barn&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;190px|||||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;3.25&#8243; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_phone=&#8221;|||&#8221; locked=&#8221;off&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h3><strong>Per applicazione: oltre 80 scenari per attrezzature di frantumazione delle rocce<\/strong><\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Paragraph&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;||0px|||&#8221;]<\/p>\n<p data-path-to-node=\"47\">L'utilit\u00e0 di un robusto <b>attrezzatura per la frantumazione delle rocce in vendita<\/b> va ben oltre la semplice bonifica del terreno. Ecco solo alcune applicazioni di alto valore in cui i nostri macchinari eccellono:<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;3.25&#8243; max_width=&#8221;800px&#8221; custom_padding=&#8221;|||&#8221; locked=&#8221;off&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Road Base Construction&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p><span class=\"citation-27 citation-end-27\">Creazione di un sottofondo stabile mediante miscelazione di aggregati con calce o cemento (stabilizzazione del terreno con calce)<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"81\"><\/sup><\/source-footnote><\/span>.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Pipeline &#038; Trench Backfill&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p>Frantumazione e miscelazione del materiale scavato in loco per un riempimento immediato e strutturalmente solido.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Airport Runway Subgrade&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p>Frantumazione e miscelazione di precisione per soddisfare i rigorosi standard delle fondazioni stradali.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;2_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Agricultural Land Reclamation&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p>Rimozione delle pietre dai campi per evitare danni ai macchinari per la successiva semina e raccolta.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Railroad Bed Preparation&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p>Stabilizzazione delle fondamenta sotto i binari per una maggiore capacit\u00e0 di carico e longevit\u00e0.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Compost Barn Management&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%36%%&#8221; icon_color=&#8221;#0469be&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;32px&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; body_font_size=&#8221;15px&#8221; body_line_height=&#8221;1.8em&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; animation=&#8221;off&#8221;]<\/p>\n<p><span class=\"citation-26\">IL <\/span><b><span class=\"citation-26\">DISTRUTTORE<\/span><\/b><span class=\"citation-26 citation-end-26\"> La serie, commercializzata principalmente per la rivoltatura dei fienili del compost, \u00e8 essenzialmente un coltivatore rotativo profondo specializzato, che dimostra la sua versatilit\u00e0 per l'aerazione e la miscelazione del terreno, ottenendo una forma di stabilizzazione organica del terreno<source-footnote ng-version=\"0.0.0-PLACEHOLDER\" _nghost-ng-c4246271013=\"\"><sup _ngcontent-ng-c4246271013=\"\" class=\"superscript\" data-turn-source-index=\"82\"><\/sup><\/source-footnote><\/span>.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;CTA Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_end=&#8221;#f2f6f9&#8243; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;75%&#8221; background_color_gradient_end_position=&#8221;75%&#8221; custom_padding=&#8221;0px|0px|120px|0px||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;1%&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; admin_label=&#8221;CTA Row&#8221; _builder_version=&#8221;3.25&#8243; background_color_gradient_direction=&#8221;90deg&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;120px|||&#8221; custom_padding_phone=&#8221;120px|0px|0px|0px&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;80px|||12%&#8221; custom_padding_tablet=&#8221;|10%||10%&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;25px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;-78px||20px|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;0px|10%||70px&#8221; custom_padding_phone=&#8221;0px|10%||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h3><strong>Per principio di funzionamento: stabilizzatore vs. frantoio<\/strong><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_color=&#8221;#21323d&#8221; header_2_font_size=&#8221;40px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|100px||70px&#8221; custom_padding_phone=&#8221;|||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p data-path-to-node=\"43\">La presa di forza (PTO) \u00e8 il cuore di qualsiasi <b>frantoio per rocce da trattore<\/b>. <span class=\"citation-30\">La scelta della macchina corretta dipende interamente dalla potenza del motore del trattore (cv\/HP) e dalla portata idraulica (<\/span><span class=\"math-inline\" data-math=\"L\/min\">litri\/min<\/span><span class=\"citation-30 citation-end-30\">)<\/span>Una potenza insufficiente in un'applicazione di frantumazione comporta un funzionamento inefficiente e un'usura prematura. <span class=\"citation-29\">IL <\/span><b><span class=\"citation-29\">THOR 3.0<\/span><\/b><span class=\"citation-29 citation-end-29\">, che richiede un minimo di 230 HP, \u00e8 progettato per letti di roccia ad alta resistenza e su larga scala, dimostrando perch\u00e9 il dimensionamento corretto \u00e8 fondamentale sia per la sicurezza che per l'efficacia<\/span>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/stone-crusher-thor3.0.webp&#8221; alt=&#8221;stone crusher thor3.0&#8243; title_text=&#8221;stone crusher thor3.0&#8243; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services Section&#8221; _builder_version=&#8221;3.22&#8243; background_color=&#8221;#f2f6f9&#8243; custom_padding=&#8221;120px|0px|120px|0px&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h2>Tipi di stabilizzatori del terreno<\/h2>\n<p>Donec id elit non mi porta gravida at egeum sociis natoque penatibus et magnis dis<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Rock Rake&#8221; url=&#8221;https:\/\/soil-stabilisor.com\/product-category\/rock-rake\/&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/ew-4000-rocke-rake-1.webp&#8221; alt=&#8221;ew-4000 rocke rake&#8221; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Rock Pickers&#8221; url=&#8221;https:\/\/soil-stabilisor.com\/product-category\/rock-pickers\/&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/ct-2100-rock-pickers-1.webp&#8221; alt=&#8221;ct-2100 rock pickers&#8221; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Rotavator&#8221; url=&#8221;https:\/\/soil-stabilisor.com\/product-category\/rotavator\/&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/psw-3200-a-rotavator-1.webp&#8221; alt=&#8221;psw-3200 a rotavator&#8221; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Mulchers \/ Stone Crushers&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/stone-crusher-thor2.4-1.webp&#8221; alt=&#8221;stone crusher thor2.4&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Potato&#8217;s Machinery&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/r-380-3-rows-potato-furrower-1.webp&#8221; alt=&#8221;r-380 3 rows potato furrower&#8221; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Rotary Cultivator&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/era-3100-3-rows-rotary-cultivator.webp&#8221; alt=&#8221;era-3100 3 rows rotary cultivator&#8221; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Montserrat|600|||||||&#8221; background_color=&#8221;#f5f5f5&#8243; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px|||10px|false|false&#8221; custom_padding=&#8221;10px|10px|10px|10px|false|false&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_text=&#8221;all services&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Stats&#8221; _builder_version=&#8221;4.8.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(33,122,206,0.7)&#8221; background_color_gradient_end=&#8221;#143d58&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/rotavator-3.webp&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;200px|0px|200px|0px&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;rgba(5,41,66,0.3)&#8221; bottom_divider_height=&#8221;12vw&#8221;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;since&#8221; number=&#8221;1970&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.8.0&#8243; title_font=&#8221;Montserrat||||||||&#8221; title_text_color=&#8221;#f4a946&#8243; title_font_size=&#8221;14px&#8221; number_font=&#8221;Montserrat|500|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;93px&#8221; background_layout=&#8221;dark&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Years in Business&#8221; number=&#8221;55&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;4.8.0&#8243; title_font=&#8221;Montserrat||||||||&#8221; title_text_color=&#8221;#f4a946&#8243; title_font_size=&#8221;14px&#8221; number_font=&#8221;Montserrat|500|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;93px&#8221; background_layout=&#8221;dark&#8221;][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_number_counter title=&#8221;Locations&#8221; number=&#8221;18&#8243; percent_sign=&#8221;off&#8221; _builder_version=&#8221;3.0.106&#8243; title_font=&#8221;Montserrat||||||||&#8221; title_text_color=&#8221;#f4a946&#8243; title_font_size=&#8221;14px&#8221; number_font=&#8221;Montserrat|500|||||||&#8221; number_text_color=&#8221;#ffffff&#8221; number_font_size=&#8221;93px&#8221; background_layout=&#8221;dark&#8221;][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;CTA Section&#8221; _builder_version=&#8221;3.22&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(242,246,249,0)&#8221; background_color_gradient_end=&#8221;#f2f6f9&#8243; background_color_gradient_direction=&#8221;90deg&#8221; background_color_gradient_start_position=&#8221;75%&#8221; background_color_gradient_end_position=&#8221;75%&#8221; custom_padding=&#8221;120px|0px|120px|0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_intensity_slide=&#8221;1%&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; admin_label=&#8221;CTA Row&#8221; _builder_version=&#8221;3.25&#8243; background_color_gradient_direction=&#8221;90deg&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;120px|||&#8221; custom_padding_phone=&#8221;120px|0px|0px|0px&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;80px|||12%&#8221; custom_padding_tablet=&#8221;|10%||10%&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;-78px||20px|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;0px|10%||70px&#8221; custom_padding_phone=&#8221;0px|10%||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; header_2_font_size_tablet=&#8221;35px&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1em&#8221; header_2_line_height_phone=&#8221;1.4em&#8221; header_2_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2>India Watanabe: garanzia di qualit\u00e0 dal produttore leader in India<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_color=&#8221;#21323d&#8221; header_2_font_size=&#8221;40px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|100px||70px&#8221; custom_padding_phone=&#8221;|||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p data-path-to-node=\"40\">Come premier <b>Produttore indiano<\/b> e competenza nell'ingegneria meccanica, sappiamo che qualit\u00e0 e fiducia si costruiscono attraverso la trasparenza e un impegno comprovato. La nostra capacit\u00e0 produttiva locale, supportata dall'eccellenza globale del gruppo Watanabe, vi garantisce componenti e macchinari che soddisfano gli standard industriali pi\u00f9 esigenti al mondo.<\/p>\n<p data-path-to-node=\"42\">\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/watanabe-factory.webp&#8221; alt=&#8221;Factory&#8221; title_text=&#8221;watanabe factory&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; background_size=&#8221;contain&#8221; background_position=&#8221;center_right&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;|60px||60px&#8221; custom_margin_phone=&#8221;100px|||&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_color=&#8221;#21323d&#8221; header_2_font_size=&#8221;40px&#8221; max_width=&#8221;800px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|100px||70px&#8221; custom_padding_phone=&#8221;|||50px&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; text_line_height_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<p data-path-to-node=\"36\">Ogni pezzo di <b>attrezzature per la frantumazione delle rocce<\/b> prodotto in India \u00e8 sottoposto a un rigoroso processo di garanzia della qualit\u00e0 in pi\u00f9 fasi:<\/p>\n<ul start=\"1\" data-path-to-node=\"37\">\n<li>\n<p data-path-to-node=\"37,0,0\"><b>Tracciabilit\u00e0 dei materiali locali:<\/b> Tutto l'acciaio strutturale e i componenti critici soggetti a usura provengono da stabilimenti indiani certificati, dotati di registri di tracciabilit\u00e0 completi, che garantiscono la conformit\u00e0 agli standard locali.<\/p>\n<\/li>\n<\/ul>\n<ul>\n<li data-path-to-node=\"37,1,0\"><b>Verifica della lavorazione di precisione:<\/b> I controlli dimensionali su tutti i componenti critici (come alberi del rotore, cuscinetti e supporti del martello) vengono eseguiti rispetto ai modelli CAD.<\/li>\n<\/ul>\n<ul>\n<li data-path-to-node=\"37,2,0\"><b>Test di integrit\u00e0 della saldatura:<\/b> I test non distruttivi (NDT) vengono applicati a tutte le saldature portanti per garantire la massima resistenza alle elevate forze d'impatto, fondamentali per la dura roccia indiana.\u00a0<\/li>\n<li data-path-to-node=\"37,3,0\"><b>Ispezione operativa finale:<\/b> Ogni unit\u00e0 viene sottoposta a un test completo simulato sul campo, verificando la stabilit\u00e0 dei giri al minuto dell'albero della presa di forza, la pressione dei fluidi e la reattivit\u00e0 della valvola idraulica prima della spedizione.<\/li>\n<\/ul>\n<p data-path-to-node=\"42\">[\/et_pb_text][et_pb_button button_text=&#8221;contact us&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.8.0&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;30px|||&#8221; custom_margin_tablet=&#8221;||120px|70px&#8221; custom_margin_phone=&#8221;||120px|50px&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services Section&#8221; _builder_version=&#8221;3.22&#8243; background_color=&#8221;#f2f6f9&#8243; custom_padding=&#8221;120px|0px|120px|0px&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h2>Approfondimento tecnico: la scienza della stabilizzazione del suolo<\/h2>\n<p>Per garantire prestazioni ottimali e longevit\u00e0 del progetto, \u00e8 essenziale comprendere i principi geotecnici sottostanti.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;3.25&#8243; max_width=&#8221;1440px&#8221; custom_padding=&#8221;|||&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;1440px&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/awb-1600-a-2-rows.webp&#8221; alt=&#8221;awb-1600 a 2 rows&#8221; title_text=&#8221;awb-1600 a 2 rows&#8221; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; locked=&#8221;off&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Service Name&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_line_height=&#8221;1.5em&#8221; custom_padding=&#8221;10px|20px||20px&#8221; locked=&#8221;off&#8221;]<\/p>\n<h3><strong>Analisi della composizione del suolo e selezione del trattamento<\/strong><\/h3>\n<p data-path-to-node=\"29\">Un'efficace stabilizzazione del suolo inizia con una corretta identificazione. Le nostre macchine sono progettate per affrontare le sfide specifiche del suolo indiano:<\/p>\n<ul data-path-to-node=\"30\">\n<li>\n<p data-path-to-node=\"30,0,0\"><b>Terreno di cotone nero (India peninsulare):<\/b> Caratterizzato da elevata plasticit\u00e0 e rigonfiamento\/restringimento estremo, che richiede un trattamento chimico come <b>stabilizzazione del terreno con calce<\/b> per scambiare cationi e ridurre la variazione di volume. Il nostro <b>Stabilizzatore del terreno<\/b> garantisce una profondit\u00e0 di miscelazione uniforme fino a <span class=\"math-inline\" data-math=\"80 cm\">$80 cm$<\/span> (Specifiche della serie DESTROYER adattate) per il massimo effetto.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"30,1,0\"><b>Terreno lateritico (India meridionale e occidentale):<\/b> Spesso ghiaioso con scarsa coesione. Miscelazione meccanica da parte del <b>frantoio per rocce<\/b> e l'aggiunta di leganti cementizi migliora significativamente la resistenza al taglio e la durevolezza, rendendolo adatto alle strade a basso traffico.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; background_color=&#8221;#ffffff&#8221; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Service Name&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_line_height=&#8221;1.5em&#8221; custom_padding=&#8221;10px|20px||20px&#8221;]<\/p>\n<h3><strong>Comprensione del CBR (California Bearing Ratio)<\/strong><\/h3>\n<p>Il valore CBR \u00e8 lo standard metrico per la valutazione della resistenza del sottofondo. I progetti di costruzione di alto livello si basano sul raggiungimento di specifici obiettivi CBR. Il nostro sistema integrato <b>frantoio per rocce<\/b> e la tecnologia stabilizzatrice consente di ottenere una base aggregata pi\u00f9 fine e uniformemente graduata (mediante la frantumazione delle rocce e l'incorporazione di particelle fini), che migliora notevolmente la compattazione e incrementa il valore CBR finale in situ, riducendo al minimo i cedimenti post-costruzione.<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/stone-crusher-thor3.0-2-1.webp&#8221; alt=&#8221;stone crusher thor3.0-2&#8243; title_text=&#8221;stone crusher thor3.0-2&#8243; force_fullwidth=&#8221;on&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.8.0&#8243; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_blur=&#8221;40px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_button button_text=&#8221;all services&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Pricing Section&#8221; _builder_version=&#8221;3.22&#8243; custom_padding=&#8221;120px|0px|120px|0px&#8221;][et_pb_row admin_label=&#8221;Section Title Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; locked=&#8221;off&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Section Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;off|desktop&#8221;]<\/p>\n<h2><strong>Centro di conoscenze approfondite su stabilizzatori e frantumatori<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Pricing Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;12%&#8221; border_color_all=&#8221;#e0e7ed&#8221; border_width_top=&#8221;1px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package Title &#038; Services with Paragraph&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_6_font=&#8221;||||||||&#8221; custom_margin=&#8221;||20px|&#8221;]<\/p>\n<h3><strong>Cos'\u00e8 un frantoio per rocce azionato da presa di forza?<\/strong><\/h3>\n<p>UN <b>Frantoio per rocce azionato da presa di forza<\/b> \u00e8 un'attrezzatura agricola o di ingegneria civile collegata all'albero della presa di forza (PTO) di un trattore. La PTO trasferisce la potenza del motore del trattore direttamente al rotore della macchina tramite un robusto riduttore, facendo girare ad alta velocit\u00e0 un tamburo con denti in carburo di tungsteno o martelli.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#94a4ae&#8221;]<\/p>\n<p>Questa azione meccanica polverizza le rocce e mescola il terreno in un unico passaggio. \u00c8 il modo pi\u00f9 potente e mobile per gestire la frantumazione di pietre su larga scala senza trasportare i materiali fuori dal sito, fungendo da efficiente <b>stabilizzatore del terreno<\/b> incorporando le sanzioni aggregate risultanti.<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Book an Appointment&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#1777cf&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; button_text_color_hover=&#8221;#e09900&#8243; button_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; locked=&#8221;off&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#e09900&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Pricing Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;12%&#8221; border_color_all=&#8221;#e0e7ed&#8221; border_width_top=&#8221;1px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package Title &#038; Services with Paragraph&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_6_font=&#8221;||||||||&#8221; custom_margin=&#8221;||20px|&#8221;]<\/p>\n<h3><strong>Come scegliere lo stabilizzatore del terreno pi\u00f9 adatto al tuo trattore?<\/strong><\/h3>\n<p>La selezione dipende interamente da tre fattori chiave:<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#94a4ae&#8221;]<\/p>\n<ul>\n<li>\n<p data-path-to-node=\"51,0,0\"><b>Materiale:<\/b> Le dimensioni e la durezza del materiale da frantumare (ad esempio, il basalto solido richiede la massima potenza, il calcare pi\u00f9 morbido \u00e8 pi\u00f9 facile).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"51,1,0\"><b>Profondit\u00e0:<\/b> Profondit\u00e0 e larghezza di lavoro richieste (la miscelazione superficiale richiede meno potenza rispetto alla riduzione profonda della roccia).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"51,2,0\"><b>Specifiche del trattore:<\/b> \u00c8 necessario abbinare la potenza minima richiesta dalla macchina (ad esempio, 230 CV per il THOR 3.0) e assicurarsi che il trattore possa fornire il flusso minimo di olio idraulico (ad esempio, <span class=\"math-inline\" data-math=\"60~L\/min.\">60~L\/min<\/span>\u00a0per i modelli EW\/CT). L'ignoranza di queste specifiche pu\u00f2 causare gravi danni all'apparecchiatura e potenziali lesioni personali.<\/p>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Book an Appointment&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#1777cf&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; button_text_color_hover=&#8221;#e09900&#8243; button_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; locked=&#8221;off&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#e09900&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;Pricing Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;12%&#8221; border_color_all=&#8221;#e0e7ed&#8221; border_width_top=&#8221;1px&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package Title &#038; Services with Paragraph&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;2.2em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;Montserrat||||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.5em&#8221; header_6_font=&#8221;||||||||&#8221; custom_margin=&#8221;||20px|&#8221;]<\/p>\n<h3><strong>Perch\u00e9 la stabilizzazione del terreno \u00e8 fondamentale per le basi stradali?<\/strong><\/h3>\n<p>La stabilizzazione del suolo \u00e8 fondamentale per la longevit\u00e0 delle infrastrutture in tutta l'India, soprattutto considerando la stagione dei monsoni e le ampie variazioni nelle tipologie di suolo. Sottofondi instabili, in particolare quelli con terreno di cotone nero, portano a cedimenti prematuri della pavimentazione (crepe, solchi) a causa di una capacit\u00e0 portante insufficiente e di un eccessivo movimento di umidit\u00e0. La stabilizzazione previene questo fenomeno:<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#94a4ae&#8221;]<\/p>\n<ul>\n<li>\n<p data-path-to-node=\"54,0,0\"><b>Aumento della resistenza al carico:<\/b> Aumentare il California Bearing Ratio (CBR) del terreno per supportare il traffico intenso sulle autostrade nazionali e sulle strade secondarie.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"54,1,0\"><b>Controllo dell'umidit\u00e0:<\/b> Lega chimicamente le molecole d'acqua (utilizzando calce\/cemento), riducendo significativamente il rigonfiamento e il restringimento nei terreni problematici.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"54,2,0\"><b>Efficienza dei costi:<\/b> L'utilizzo di materiali locali, in situ, miscelati con leganti \u00e8 spesso molto pi\u00f9 conveniente rispetto all'importazione di aggregati vergini, in linea con l'attenzione rivolta allo sviluppo di infrastrutture sostenibili ed economiche in India.<\/p>\n<p data-path-to-node=\"82,0,0\">\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Book an Appointment&#8221; _builder_version=&#8221;3.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#1777cf&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; button_text_color_hover=&#8221;#e09900&#8243; button_bg_color_hover=&#8221;rgba(0,0,0,0)&#8221; locked=&#8221;off&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;on&#8221; button_text_color__hover=&#8221;#e09900&#8243; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;on&#8221; button_bg_color__hover=&#8221;rgba(0,0,0,0)&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;VIdeo Section&#8221; _builder_version=&#8221;4.8.0&#8243; background_image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/potato-diggers.webp&#8221; min_height=&#8221;500px&#8221; custom_padding=&#8221;0px|0px|81px|0px||&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;40px&#8221; box_shadow_vertical=&#8221;40px&#8221; box_shadow_blur=&#8221;120px&#8221; box_shadow_spread=&#8221;-24px&#8221; box_shadow_color=&#8221;rgba(67,96,124,0.5)&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0px|0px&#8221; make_fullwidth=&#8221;on&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_video_slider _builder_version=&#8221;4.8.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_video_slider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Testimonials&#8221; _builder_version=&#8221;3.22&#8243; custom_padding=&#8221;120px|0px|120px|0px&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; border_color_bottom=&#8221;#e8e8e8&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;18px&#8221; header_font=&#8221;||||||||&#8221; header_line_height=&#8221;1.4em&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;40px&#8221; header_2_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;|||&#8221; text_font_size_tablet=&#8221;16px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<h2>Clienti soddisfatti<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;3.25&#8243; max_width=&#8221;1440px&#8221; custom_padding=&#8221;50px|0px|50px|0px&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#e8e8e8&#8243; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;1440px&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/stars-5.png&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.23&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Clients Testimonial&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|300|on||||||&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;2em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221;]<\/p>\n<p>\"Il supporto locale del team India Watanabe \u00e8 stato un vantaggio cruciale. Avevamo bisogno di un pezzo di ricambio in tempi rapidi e ce l'hanno consegnato entro 48 ore presso la nostra sede remota, evitando costosi ritardi. Questo livello di dedizione, unito alla qualit\u00e0 superiore della macchina, dimostra perch\u00e9 scegliere un'azienda locale <b>Produttore indiano<\/b> fa tutta la differenza.\"<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Karnataka, India &#8211; Infrastructure Project Manager&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/portrait-square-03.jpg&#8221; image_max_width=&#8221;50px&#8221; admin_label=&#8221;Client Info &#038; Avatar&#8221; _builder_version=&#8221;3.0.106&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; text_orientation=&#8221;center&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_radii_image=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style_image=&#8221;preset3&#8243;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/stars-5.png&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.23&#8243; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; locked=&#8221;off&#8221;][\/et_pb_image][et_pb_text admin_label=&#8221;Clients Testimonial&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat|300|on||||||&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;2em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; locked=&#8221;off&#8221;]<\/p>\n<p>\"La durata del martello \u00e8 la migliore che abbiamo mai visto. In passato, sostituivamo i martelli ogni poche settimane. Con il <b>THOR 3.0<\/b> modello, la frequenza di sostituzione \u00e8 diminuita significativamente. Per un gestore di cava, ridurre al minimo i costi dei materiali di consumo \u00e8 fondamentale, e questo robusto <b>frantoio per rocce da trattore<\/b> L'accessorio si sta rivelando un macchinario molto conveniente.\"<\/p>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Gujarat, India &#8211; Quarry Manager&#8221; image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/portrait-square-08.jpg&#8221; image_max_width=&#8221;50px&#8221; admin_label=&#8221;Client Info &#038; Avatar&#8221; _builder_version=&#8221;3.0.106&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat||||||||&#8221; text_orientation=&#8221;center&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_radii_image=&#8221;on|100px|100px|100px|100px&#8221; box_shadow_style_image=&#8221;preset3&#8243; locked=&#8221;off&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer Section&#8221; _builder_version=&#8221;4.8.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(20,61,88,0.65)&#8221; background_color_gradient_end=&#8221;#143d58&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/rock-pickers.webp&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;6vw|0px|3vw|0px||&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;rgba(5,41,66,0.3)&#8221; bottom_divider_height=&#8221;50%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;6%&#8221; animation_starting_opacity=&#8221;100%&#8221; saved_tabs=&#8221;all&#8221;][et_pb_row admin_label=&#8221;Footer Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;3.27.4&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#a4bccb&#8221; text_font_size=&#8221;20px&#8221; text_line_height=&#8221;1.5em&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Montserrat||||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;Montserrat|500|||||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_font_size=&#8221;55px&#8221; header_3_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px|&#8221; header_3_font_size_tablet=&#8221;60px&#8221; header_3_font_size_phone=&#8221;52px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221;]<\/p>\n<h2>Negozio di stabilizzatori del terreno a servizio completo<\/h2>\n<h3>Soddisfazione garantita<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8221;CTA Row&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;mail us today&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;%%109%%&#8221; icon_color=&#8221;#FFFFFF&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;40px&#8221; admin_label=&#8221;CTA&#8221; _builder_version=&#8221;4.8.0&#8243; header_font=&#8221;Montserrat||||||||&#8221; header_text_color=&#8221;#a4bccb&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Montserrat|500|||||||&#8221; body_text_align=&#8221;center&#8221; body_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; animation=&#8221;off&#8221;]<\/p>\n<p><a href=\"mailto:sales@soil-stabilisor.com\">sales@soil-stabilisor.com<\/a><\/p>\n<p>O<\/p>\n<p>[\/et_pb_blurb][et_pb_button button_text=&#8221;Concact us&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;CTA Button&#8221; _builder_version=&#8221;4.8.0&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#f6961b&#8221; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#f6961b&#8221; button_border_radius=&#8221;2px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;Montserrat|700||on|||||&#8221; custom_margin=&#8221;30px|||&#8221; custom_padding=&#8221;|||&#8221; button_border_radius_hover=&#8221;4px&#8221; locked=&#8221;off&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;on&#8221; button_border_radius__hover=&#8221;4px&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Header Section&#8221; _builder_version=&#8221;4.8.0&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(20,61,88,0.65)&#8221; background_color_gradient_end=&#8221;#143d58&#8243; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/soil-stabilisor.com\/wp-content\/uploads\/2025\/11\/rock-rake.webp&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;16vw|0px|16vw|0px&#8221; bottom_divider_style=&#8221;mountains2&#8243; bottom_divider_color=&#8221;rgba(5,41,66,0.3)&#8221; bottom_divider_height=&#8221;50%&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;4%&#8221; animation_starting_opacity=&#8221;100%&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Header Row&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;3.25&#8243; width=&#8221;89%&#8221; width_tablet=&#8221;80%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;89%&#8221; max_width_tablet=&#8221;80%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;|||&#8221; animation_style=&#8221;zoom&#8221; animation_intensity_zoom=&#8221;8%&#8221; make_fullwidth=&#8221;on&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Page Heading &#038; Subhead&#8221; _builder_version=&#8221;4.8.0&#8243; text_font=&#8221;Montserrat||||||||&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;Montserrat|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;8vw&#8221; header_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-73","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/pages\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":18,"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":377,"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/pages\/73\/revisions\/377"}],"wp:attachment":[{"href":"https:\/\/soil-stabilisor.com\/it\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}